{"id":275,"date":"2022-12-21T11:38:17","date_gmt":"2022-12-21T11:38:17","guid":{"rendered":"https:\/\/aresca.eu\/?p=275"},"modified":"2025-02-20T15:12:18","modified_gmt":"2025-02-20T15:12:18","slug":"biomarket-aresca","status":"publish","type":"post","link":"https:\/\/aresca.eu\/esp\/biomarket-aresca\/","title":{"rendered":"BIOmarket Aresca"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/aresca.eu\/wp-content\/uploads\/2022\/11\/camp-arros.jpg\u00bb parallax=\u00bbon\u00bb height=\u00bb50vh\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb height=\u00bb100%\u00bb custom_css_main_element=\u00bbdisplay: flex;||flex-direction: column;||justify-content: center;\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbRaleway|800||on|||||\u00bb header_text_color=\u00bb#FFFFFF\u00bb header_font_size=\u00bb60px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>BIOmarket aresca<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png\u00bb alt=\u00bbDibuix d&#8217;una tenda de fruites\u00bb title_text=\u00bbDibuix d&#8217;una tenda de fruites\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbPoppins|300|||||||\u00bb global_colors_info=\u00bb{}\u00bb]<span style=\"font-weight: 500;\">Filosof\u00eda<\/span><\/p>\n<p>\u2013 Promover el desarrollo de la agricultura ecol\u00f3gica.<\/p>\n<p>- Promoci\u00f3n del medio rural y la sostenibilidad de las actividades.<\/p>\n<p>\u2013 Crecimiento de la empresa y expansi\u00f3n internacional.<\/p>\n<p>\u2013 Apoyo y fomento de la comercializaci\u00f3n de productos ecol\u00f3gicos, para facilitar la consolidaci\u00f3n de este sector en el conjunto del mercado alimenticio.<\/p>\n<p>\u2013 Mejorar el conocimiento del producto ecol\u00f3gico y promover su comercializaci\u00f3n y su consumo.<\/p>\n<p><span style=\"font-weight: 500;\">\u00bfPor qu\u00e9 trabajar con nuestro producto?<\/span><\/p>\n<p>El \u00c9xito del producto ecol\u00f3gico con el que trabajaremos, tendr\u00e1 las siguientes cualidades:<\/p>\n<p>\u2013 Su naturaleza y caracter\u00edsticas intr\u00ednsecas<\/p>\n<p>\u2013 Sus prestaciones y valores a\u00f1adidos<\/p>\n<p>\u2013 Sus ventajas competitivas sobre otros productos similares o sustitutivos<\/p>\n<p><span style=\"font-weight: 500;\">Aportaciones Profesionales:<\/span><\/p>\n<p>\u2013 Experiencia de la empresa<\/p>\n<p>\u2013 Pagos puntuales<\/p>\n<p>\u2013 Rapidez de entrega<\/p>\n<p>\u2013 Propuesta adaptada y personalizada al cliente<\/p>\n<p>\u2013 Calidad por encima de cantidad<\/p>\n<p><span style=\"font-weight: 500;\">BIOmarket Aresca Fruits sl.<\/span><\/p>\n<p>Cuenta con apoyo institucional y cuenta con el gran apoyo del Mercado Central de Frutas y Hortalizas de Barcelona. Aportamos novedades a la evoluci\u00f3n del producto ecol\u00f3gico, desarrollando nuevas tendencias y nuevos mercados con r\u00e1pido avance de las exportaciones.<\/p>\n<p><span style=\"font-weight: 500;\">Aportaciones a su empresa<\/span><\/p>\n<p>\u2013 Innovaci\u00f3n, la introducci\u00f3n de un producto clave, en la alimentaci\u00f3n de hoy en d\u00eda.<\/p>\n<p>\u2013 Resultados positivos comprobados y en auge, en el mercado convencional.<\/p>\n<p>\u2013 Dinamismo, te proporcionamos soluciones de inmediato.<\/p>\n<p>\u2013 Trato personalizado, seg\u00fan necesidades.<\/p>\n<p>\u2013 Lanzamiento junto a Aresca Fruits sl. en el mercado m\u00e1s importante de Espa\u00f1a, Mercabarna.<\/p>\n<p>\u2013 Progreso en el mercado ecol\u00f3gico, actualmente, en constante crecimiento de la producci\u00f3n ecol\u00f3gica, en pa\u00edses emergentes.<\/p>\n<p><span style=\"font-weight: 500;\">\u00a1Comunicaremos mediante nuestras redes sociales la pr\u00f3xima apertura!<\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb1300px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbPoppins|600|||||||\u00bb header_2_font=\u00bbPoppins|500|||||||\u00bb custom_margin=\u00bb||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 data-fontsize=\"32\" data-lineheight=\"41\" style=\"text-align: left;\">Informaci\u00f3n de contacto<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=\u00bb#fcdb5a\u00bb divider_position=\u00bbcenter\u00bb divider_weight=\u00bb2px\u00bb _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb250px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_blurb title=\u00bb+34 933 35 15 39&#8243; url=\u00bbtel:%20+34%20933%2035%2015%2039&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf879;||fa||900&#8243; icon_color=\u00bb#fcdb5a\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bbPoppins||||||||\u00bb header_font_size=\u00bb18px\u00bb custom_css_blurb_title=\u00bbpadding-top: 5px;||padding-left: 10px;\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbMERCABARNA PAVELL\u00d3 B 2027\/28 I C 3017\/18, 08040 Barcelona\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe080;||divi||400&#8243; icon_color=\u00bb#fcdb5a\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.22.2&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bbPoppins||||||||\u00bb header_font_size=\u00bb15px\u00bb custom_css_blurb_title=\u00bbpadding-top: 5px;||padding-left: 10px;\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbaresca@aresca.eu\u00bb url=\u00bbmailto:aresca@aresca.eu\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#fcdb5a\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_level=\u00bbh3&#8243; header_font=\u00bbPoppins||||||||\u00bb header_font_size=\u00bb18px\u00bb hover_enabled=\u00bb0&#8243; custom_css_blurb_title=\u00bbpadding-top: 5px;||padding-left: 10px;\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bbPoppins|600|||||||\u00bb header_2_font=\u00bbPoppins|500|||||||\u00bb custom_margin=\u00bb||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 data-fontsize=\"32\" data-lineheight=\"41\" style=\"text-align: left;\">Formulario<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=\u00bb#fcdb5a\u00bb divider_position=\u00bbcenter\u00bb divider_weight=\u00bb2px\u00bb _builder_version=\u00bb4.17.1&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb250px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_contact_form use_spam_service=\u00bbon\u00bb recaptcha_list=\u00bbDefault|Default-0&#8243; email=\u00bbaresca@aresca.eu\u00bb custom_message=\u00bbMensaje del formulario de aresca.eu||et_pb_line_break_holder||||et_pb_line_break_holder||Nombre: %%Name%%||et_pb_line_break_holder||Tel\u00e9fono: %%Telefon%%||et_pb_line_break_holder||Email: %%Email%%||et_pb_line_break_holder||Mensaje: %%Message%%\u00bb submit_button_text=\u00bbEnvia\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb _unique_id=\u00bb20bffa56-eae1-4940-9a0e-452dfd6986fb\u00bb form_field_background_color=\u00bb#FFFFFF\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#fcdb5a\u00bb button_border_width=\u00bb0px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_margin_tablet=\u00bb||||false|true\u00bb custom_margin_last_edited=\u00bboff|phone\u00bb border_width_all=\u00bb2px\u00bb border_color_all=\u00bb#fcdb5a\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbNom *\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbTelefon\u00bb field_title=\u00bbTel\u00e8fon\u00bb required_mark=\u00bboff\u00bb _builder_version=\u00bb4.27.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbAdre\u00e7a de correu electr\u00f2nic *\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.27.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMissatge *\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.27.0&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbField_4&#8243; field_title=\u00bb \u00bb field_type=\u00bbcheckbox\u00bb checkbox_options=\u00bb%91{%22value%22:%22 Accepto la %22,%22checked%22:0,%22dragID%22:-1,%22link_url%22:%22https:\/\/aresca.eu\/politica-de-privacitat%22,%22link_text%22:%22Pol\u00edtica de privacitat%22}%93&#8243; fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.22.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb link_font=\u00bb|600|||||||\u00bb link_text_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Este sitio est\u00e1 protegido por reCAPTCHA y se aplican la <a href=\"https:\/\/policies.google.com\/privacy\" role=\"link\">Pol\u00edtica de privacidad<\/a> y las <a href=\"https:\/\/policies.google.com\/terms\" role=\"link\">Condiciones del servicio<\/a> de Google.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Filosof\u00eda<\/p>\n<p>\u2013 Promover el desarrollo de la agricultura ecol\u00f3gica.<\/p>\n<p>- Promoci\u00f3n del medio rural y la sostenibilidad de las actividades.<\/p>\n<p>\u2013 Crecimiento de la empresa y expansi\u00f3n internacional.<\/p>\n<p>- Apoyo y fomento de la comercializaci\u00f3n de productos ecol\u00f3gicos, para facilitar la consolidaci\u00f3n de este sector en el conjunto del mercado alimenticio.<\/p>\n<p>\u2013 Mejorar el conocimiento del producto ecol\u00f3gico y promover su comercializaci\u00f3n y su consumo.<\/p>","protected":false},"author":1,"featured_media":277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[1],"tags":[],"class_list":["post-275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BIOmarket Aresca - Aresca Fruits<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aresca.eu\/esp\/biomarket-aresca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BIOmarket Aresca - Aresca Fruits\" \/>\n<meta property=\"og:description\" content=\"Filosofia \u2013 Promoure el desenvolupament de l\u2019agricultura ecol\u00f2gica. \u2013 Promoci\u00f3 del medi rural i la sostenibilitat de les activitats. \u2013 Creixement de l\u2019empresa i expansi\u00f3 internacional. \u2013 Suport i foment de la comercialitzaci\u00f3 de productes ecol\u00f2gics, per facilitar la consolidaci\u00f3 d\u2019aquest sector en el conjunt del mercat alimentari. \u2013 Millorar el coneixement del producte ecol\u00f2gic i promoure\u2019n la comercialitzaci\u00f3 i el consum.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aresca.eu\/esp\/biomarket-aresca\/\" \/>\n<meta property=\"og:site_name\" content=\"Aresca Fruits\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61550322404597\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T11:38:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T15:12:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"429\" \/>\n\t<meta property=\"og:image:height\" content=\"376\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"assisoft\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assisoft\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/\"},\"author\":{\"name\":\"assisoft\",\"@id\":\"https:\/\/aresca.eu\/#\/schema\/person\/a784fc87d7f632b7325be83883d65432\"},\"headline\":\"BIOmarket Aresca\",\"datePublished\":\"2022-12-21T11:38:17+00:00\",\"dateModified\":\"2025-02-20T15:12:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/\"},\"wordCount\":1678,\"publisher\":{\"@id\":\"https:\/\/aresca.eu\/#organization\"},\"image\":{\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/\",\"url\":\"https:\/\/aresca.eu\/biomarket-aresca\/\",\"name\":\"BIOmarket Aresca - Aresca Fruits\",\"isPartOf\":{\"@id\":\"https:\/\/aresca.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png\",\"datePublished\":\"2022-12-21T11:38:17+00:00\",\"dateModified\":\"2025-02-20T15:12:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aresca.eu\/biomarket-aresca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/#primaryimage\",\"url\":\"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png\",\"contentUrl\":\"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png\",\"width\":429,\"height\":376,\"caption\":\"Dibuix d'una parada d'Aresca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aresca.eu\/biomarket-aresca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/aresca.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BIOmarket Aresca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aresca.eu\/#website\",\"url\":\"https:\/\/aresca.eu\/\",\"name\":\"Aresca Fruits\",\"description\":\"Fruita fresca i saludable\",\"publisher\":{\"@id\":\"https:\/\/aresca.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aresca.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aresca.eu\/#organization\",\"name\":\"Aresca Fruits\",\"url\":\"https:\/\/aresca.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aresca.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aresca.eu\/wp-content\/uploads\/2023\/08\/logo-aresca.png\",\"contentUrl\":\"https:\/\/aresca.eu\/wp-content\/uploads\/2023\/08\/logo-aresca.png\",\"width\":224,\"height\":200,\"caption\":\"Aresca Fruits\"},\"image\":{\"@id\":\"https:\/\/aresca.eu\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61550322404597\",\"https:\/\/www.instagram.com\/arescafruitss.l\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/aresca.eu\/#\/schema\/person\/a784fc87d7f632b7325be83883d65432\",\"name\":\"assisoft\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aresca.eu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/aresca.eu\/wp-content\/litespeed\/avatar\/0ee51eaac491861c051954dde15c2d6e.jpg?ver=1783349976\",\"contentUrl\":\"https:\/\/aresca.eu\/wp-content\/litespeed\/avatar\/0ee51eaac491861c051954dde15c2d6e.jpg?ver=1783349976\",\"caption\":\"assisoft\"},\"sameAs\":[\"https:\/\/aresca.eu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BIOmarket Aresca - Aresca Fruits","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aresca.eu\/esp\/biomarket-aresca\/","og_locale":"es_ES","og_type":"article","og_title":"BIOmarket Aresca - Aresca Fruits","og_description":"Filosofia \u2013 Promoure el desenvolupament de l\u2019agricultura ecol\u00f2gica. \u2013 Promoci\u00f3 del medi rural i la sostenibilitat de les activitats. \u2013 Creixement de l\u2019empresa i expansi\u00f3 internacional. \u2013 Suport i foment de la comercialitzaci\u00f3 de productes ecol\u00f2gics, per facilitar la consolidaci\u00f3 d\u2019aquest sector en el conjunt del mercat alimentari. \u2013 Millorar el coneixement del producte ecol\u00f2gic i promoure\u2019n la comercialitzaci\u00f3 i el consum.","og_url":"https:\/\/aresca.eu\/esp\/biomarket-aresca\/","og_site_name":"Aresca Fruits","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61550322404597","article_published_time":"2022-12-21T11:38:17+00:00","article_modified_time":"2025-02-20T15:12:18+00:00","og_image":[{"width":429,"height":376,"url":"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png","type":"image\/png"}],"author":"assisoft","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assisoft","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aresca.eu\/biomarket-aresca\/#article","isPartOf":{"@id":"https:\/\/aresca.eu\/biomarket-aresca\/"},"author":{"name":"assisoft","@id":"https:\/\/aresca.eu\/#\/schema\/person\/a784fc87d7f632b7325be83883d65432"},"headline":"BIOmarket Aresca","datePublished":"2022-12-21T11:38:17+00:00","dateModified":"2025-02-20T15:12:18+00:00","mainEntityOfPage":{"@id":"https:\/\/aresca.eu\/biomarket-aresca\/"},"wordCount":1678,"publisher":{"@id":"https:\/\/aresca.eu\/#organization"},"image":{"@id":"https:\/\/aresca.eu\/biomarket-aresca\/#primaryimage"},"thumbnailUrl":"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png","articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aresca.eu\/biomarket-aresca\/","url":"https:\/\/aresca.eu\/biomarket-aresca\/","name":"BIOmarket Aresca - Aresca Fruits","isPartOf":{"@id":"https:\/\/aresca.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aresca.eu\/biomarket-aresca\/#primaryimage"},"image":{"@id":"https:\/\/aresca.eu\/biomarket-aresca\/#primaryimage"},"thumbnailUrl":"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png","datePublished":"2022-12-21T11:38:17+00:00","dateModified":"2025-02-20T15:12:18+00:00","breadcrumb":{"@id":"https:\/\/aresca.eu\/biomarket-aresca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aresca.eu\/biomarket-aresca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aresca.eu\/biomarket-aresca\/#primaryimage","url":"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png","contentUrl":"https:\/\/aresca.eu\/wp-content\/uploads\/2022\/12\/dibuix-parada.png","width":429,"height":376,"caption":"Dibuix d'una parada d'Aresca"},{"@type":"BreadcrumbList","@id":"https:\/\/aresca.eu\/biomarket-aresca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/aresca.eu\/"},{"@type":"ListItem","position":2,"name":"BIOmarket Aresca"}]},{"@type":"WebSite","@id":"https:\/\/aresca.eu\/#website","url":"https:\/\/aresca.eu\/","name":"Aresca Fruits","description":"Fruita fresca i saludable","publisher":{"@id":"https:\/\/aresca.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aresca.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aresca.eu\/#organization","name":"Aresca Fruits","url":"https:\/\/aresca.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aresca.eu\/#\/schema\/logo\/image\/","url":"https:\/\/aresca.eu\/wp-content\/uploads\/2023\/08\/logo-aresca.png","contentUrl":"https:\/\/aresca.eu\/wp-content\/uploads\/2023\/08\/logo-aresca.png","width":224,"height":200,"caption":"Aresca Fruits"},"image":{"@id":"https:\/\/aresca.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61550322404597","https:\/\/www.instagram.com\/arescafruitss.l\/"]},{"@type":"Person","@id":"https:\/\/aresca.eu\/#\/schema\/person\/a784fc87d7f632b7325be83883d65432","name":"assisoft","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aresca.eu\/#\/schema\/person\/image\/","url":"https:\/\/aresca.eu\/wp-content\/litespeed\/avatar\/0ee51eaac491861c051954dde15c2d6e.jpg?ver=1783349976","contentUrl":"https:\/\/aresca.eu\/wp-content\/litespeed\/avatar\/0ee51eaac491861c051954dde15c2d6e.jpg?ver=1783349976","caption":"assisoft"},"sameAs":["https:\/\/aresca.eu"]}]}},"_links":{"self":[{"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/posts\/275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/comments?post=275"}],"version-history":[{"count":14,"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/posts\/275\/revisions"}],"predecessor-version":[{"id":1834,"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/posts\/275\/revisions\/1834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/media\/277"}],"wp:attachment":[{"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/media?parent=275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/categories?post=275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aresca.eu\/esp\/wp-json\/wp\/v2\/tags?post=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}